{"id":10104970,"date":"2025-10-09T11:51:20","date_gmt":"2025-10-09T09:51:20","guid":{"rendered":"https:\/\/bonjourgeneve.ch\/?post_type=tribe_events&#038;p=11407"},"modified":"2026-05-08T15:22:07","modified_gmt":"2026-05-08T13:22:07","slug":"atelier-de-backgammon","status":"publish","type":"tribe_events","link":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/","title":{"rendered":"Atelier de backgammon"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":11323,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10104970","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atelier de backgammon - Bonjour Gen\u00e8ve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atelier de backgammon - Bonjour Gen\u00e8ve\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonjour Gen\u00e8ve\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T13:22:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/\",\"url\":\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/\",\"name\":\"Atelier de backgammon - Bonjour Gen\u00e8ve\",\"isPartOf\":{\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png\",\"datePublished\":\"2025-10-09T09:51:20+00:00\",\"dateModified\":\"2026-05-08T13:22:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#primaryimage\",\"url\":\"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png\",\"contentUrl\":\"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png\",\"width\":2000,\"height\":1410},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/bonjourgeneve.ch\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e8nements\",\"item\":\"https:\/\/bonjourgeneve.ch\/evenements\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Atelier de backgammon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/#website\",\"url\":\"https:\/\/bonjourgeneve.ch\/en\/\",\"name\":\"Bonjour Gen\u00e8ve\",\"description\":\"The Hospice General welcomes you to Geneva\",\"publisher\":{\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bonjourgeneve.ch\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/#organization\",\"name\":\"Bonjour Gen\u00e8ve\",\"url\":\"https:\/\/bonjourgeneve.ch\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2017\/07\/apple-touch-icon-180x180.png\",\"contentUrl\":\"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2017\/07\/apple-touch-icon-180x180.png\",\"width\":180,\"height\":180,\"caption\":\"Bonjour Gen\u00e8ve\"},\"image\":{\"@id\":\"https:\/\/bonjourgeneve.ch\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atelier de backgammon - Bonjour Gen\u00e8ve","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/","og_locale":"en_US","og_type":"article","og_title":"Atelier de backgammon - Bonjour Gen\u00e8ve","og_url":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/","og_site_name":"Bonjour Gen\u00e8ve","article_modified_time":"2026-05-08T13:22:07+00:00","og_image":[{"width":2000,"height":1410,"url":"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/","url":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/","name":"Atelier de backgammon - Bonjour Gen\u00e8ve","isPartOf":{"@id":"https:\/\/bonjourgeneve.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#primaryimage"},"image":{"@id":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#primaryimage"},"thumbnailUrl":"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png","datePublished":"2025-10-09T09:51:20+00:00","dateModified":"2026-05-08T13:22:07+00:00","breadcrumb":{"@id":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#primaryimage","url":"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png","contentUrl":"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2025\/10\/Backgammon.png","width":2000,"height":1410},{"@type":"BreadcrumbList","@id":"https:\/\/bonjourgeneve.ch\/en\/evenement\/atelier-de-backgammon\/2027-05-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bonjourgeneve.ch\/en\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e8nements","item":"https:\/\/bonjourgeneve.ch\/evenements\/"},{"@type":"ListItem","position":3,"name":"Atelier de backgammon"}]},{"@type":"WebSite","@id":"https:\/\/bonjourgeneve.ch\/en\/#website","url":"https:\/\/bonjourgeneve.ch\/en\/","name":"Bonjour Gen\u00e8ve","description":"The Hospice General welcomes you to Geneva","publisher":{"@id":"https:\/\/bonjourgeneve.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonjourgeneve.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bonjourgeneve.ch\/en\/#organization","name":"Bonjour Gen\u00e8ve","url":"https:\/\/bonjourgeneve.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bonjourgeneve.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2017\/07\/apple-touch-icon-180x180.png","contentUrl":"https:\/\/bonjourgeneve.ch\/wp-content\/uploads\/2017\/07\/apple-touch-icon-180x180.png","width":180,"height":180,"caption":"Bonjour Gen\u00e8ve"},"image":{"@id":"https:\/\/bonjourgeneve.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/tribe_events\/10104970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/tribe_events\/10104970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/media\/11323"}],"wp:attachment":[{"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/media?parent=10104970"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/tags?post=10104970"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/bonjourgeneve.ch\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10104970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}